{"id":3067,"date":"2020-03-02T10:25:31","date_gmt":"2020-03-02T10:25:31","guid":{"rendered":"https:\/\/medicinespatentpool.org\/progress-achievements\/licences\/"},"modified":"2024-10-01T17:19:52","modified_gmt":"2024-10-01T15:19:52","slug":"licences","status":"publish","type":"page","link":"https:\/\/medicinespatentpool.org\/fr\/progress-achievements\/licences","title":{"rendered":"Accords avec les innovateurs"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Le travail principal du Medicines Patent Pool consiste \u00e0 n\u00e9gocier des licences ax\u00e9es sur la sant\u00e9 publique avec les d\u00e9tenteurs de brevets, puis \u00e0 accorder des sous-licences aux fabricants de g\u00e9n\u00e9riques et aux d\u00e9veloppeurs de produits, et \u00e0 soutenir l\u2019acc\u00e8s aux traitements dans les pays \u00e0 revenu faible et interm\u00e9diaire (PRFI).<\/p>\n","protected":false},"author":1,"featured_media":6230,"parent":3064,"menu_order":29,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-3067","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/medicinespatentpool.org\/fr\/wp-json\/wp\/v2\/pages\/3067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medicinespatentpool.org\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/medicinespatentpool.org\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/medicinespatentpool.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/medicinespatentpool.org\/fr\/wp-json\/wp\/v2\/comments?post=3067"}],"version-history":[{"count":4,"href":"https:\/\/medicinespatentpool.org\/fr\/wp-json\/wp\/v2\/pages\/3067\/revisions"}],"predecessor-version":[{"id":18199,"href":"https:\/\/medicinespatentpool.org\/fr\/wp-json\/wp\/v2\/pages\/3067\/revisions\/18199"}],"up":[{"embeddable":true,"href":"https:\/\/medicinespatentpool.org\/fr\/wp-json\/wp\/v2\/pages\/3064"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medicinespatentpool.org\/fr\/wp-json\/wp\/v2\/media\/6230"}],"wp:attachment":[{"href":"https:\/\/medicinespatentpool.org\/fr\/wp-json\/wp\/v2\/media?parent=3067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}